{"id":17128,"date":"2024-04-22T15:41:43","date_gmt":"2024-04-22T18:41:43","guid":{"rendered":"https:\/\/capivari.sp.gov.br\/portal\/?p=17128"},"modified":"2024-04-22T15:41:43","modified_gmt":"2024-04-22T18:41:43","slug":"veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024","status":"publish","type":"post","link":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/","title":{"rendered":"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024"},"content":{"rendered":"<p>No \u00faltimo domingo, dia 21, teve in\u00edcio a segunda rodada do Campeonato Veterano de Futebol Amador. O dia tamb\u00e9m contou com a conclus\u00e3o da primeira rodada, totalizando tr\u00eas jogos em duas localidades diferentes. Veteranos Elias Fausto e Central venceram seus jogos e foram as manchetes do dia, no torneio que conta com a presen\u00e7a apenas de atletas com pelo menos 38 anos de idade.<\/p>\n<p>O primeiro jogo aconteceu \u00e0s 08h20 no est\u00e1dio Fernando de Marco, bairro Esta\u00e7\u00e3o, entre Bem Bolado e MM Souza\/Deportivo. Em partida eletrizante do in\u00edcio ao fim que contou com transmiss\u00e3o ao vivo dentro do programa \u201cApito Inicial\u201d, com C\u00e9lio Amorim, Leonardo Nocete e Thalles Cristiano, as equipes ficaram no empate por 2-2, com gols anotados por Erlison e J\u00fanior para o Bem Bolado e dois gols de M\u00e1rcio para o MM Souza\/Desportivo. Com o resultado, ambas equipes chegam a quatro pontos, precisando apenas de um empate na rodada final para se classificar.<\/p>\n<p>J\u00e1 o segundo duelo teve in\u00edcio \u00e0s 09h no est\u00e1dio Carlos Colnaghi, bairro S\u00e3o Jos\u00e9, entre Veteranos Elias Fausto e Ativa, ainda parte da primeira rodada da competi\u00e7\u00e3o. Ap\u00f3s 80 minutos de disputa, a equipe da cidade vizinha acabou vitoriosa pelo placar de 1-0, com gol anotado por Cleber. Com o resultado, o Veteranos Elias Fausto somam os seus primeiros tr\u00eas pontos da competi\u00e7\u00e3o, tomando a ponta do grupo B que ainda conta com a presen\u00e7a de Santa Rosa e Boca Juniors.<\/p>\n<p>Encerrando as emo\u00e7\u00f5es do dia, Gueto e Central fizeram um jogo emocionante \u00e0s 10h no est\u00e1dio Fernando de Marco, que tamb\u00e9m teve transmiss\u00e3o dentro do programa \u201cApito Inicial\u201d. Com gols de Branco e Roni, a equipe do Central venceu por 2-1 e seguiu viva na competi\u00e7\u00e3o. O Gueto, que descontou o com tento anotado por Giovani, chega a segunda derrota em dois jogos e j\u00e1 est\u00e1 matematicamente eliminada da competi\u00e7\u00e3o.<\/p>\n<p>No pr\u00f3ximo fim de semana, outras tr\u00eas partidas acontecem, encaminhando o torneio para o desfecho de sua primeira fase. Ativa e Boca Juniors se enfrentam no est\u00e1dio Fernando de Marco as 08h20, seguido pelo jogo entre Santa Rosa e Veteranos Elias Fausto, concluindo dessa forma a segunda rodada da fase de grupos. Ainda no domingo, \u00e0s 09h no est\u00e1dio Carlos Colnaghi, MM Souza\/Deportivo e Central abrem os trabalhos da terceira rodada.<\/p>\n<p>Para saber mais sobre outros projetos e torneios organizados pela Secretaria de Esportes, os telefones (19) 2146-1525 e (19) 3492-8881 (WhatsApp), est\u00e3o dispon\u00edveis de segunda a sexta-feira, das 8h30 \u00e0s 16h30.<\/p>\n<p>Prefeitura de Capivari. Transformando o presente, construindo o futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo domingo, dia 21, teve in\u00edcio a segunda rodada do Campeonato Veterano de Futebol Amador. O dia tamb\u00e9m contou com a conclus\u00e3o da primeira rodada, totalizando tr\u00eas jogos em duas localidades diferentes. Veteranos Elias Fausto e Central venceram seus jogos e foram as manchetes do dia, no torneio que conta com a presen\u00e7a apenas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[4,25,5],"tags":[],"class_list":["post-17128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-esporte","category-geral","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024 - Prefeitura de Capivari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024 - Prefeitura de Capivari\" \/>\n<meta property=\"og:description\" content=\"No \u00faltimo domingo, dia 21, teve in\u00edcio a segunda rodada do Campeonato Veterano de Futebol Amador. O dia tamb\u00e9m contou com a conclus\u00e3o da primeira rodada, totalizando tr\u00eas jogos em duas localidades diferentes. Veteranos Elias Fausto e Central venceram seus jogos e foram as manchetes do dia, no torneio que conta com a presen\u00e7a apenas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura de Capivari\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PrefeituradeCapivari\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T18:41:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/04\/fernando-de-marco-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1840\" \/>\n\t<meta property=\"og:image:height\" content=\"1004\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thalles Cristiano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PrefCapivari\" \/>\n<meta name=\"twitter:site\" content=\"@PrefCapivari\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thalles Cristiano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/\"},\"author\":{\"name\":\"Thalles Cristiano\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/person\\\/98801614a91d449946b0687ae2db9f29\"},\"headline\":\"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024\",\"datePublished\":\"2024-04-22T18:41:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fernando-de-marco-2.jpg\",\"articleSection\":[\"Destaque\",\"Esporte\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/\",\"name\":\"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024 - Prefeitura de Capivari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fernando-de-marco-2.jpg\",\"datePublished\":\"2024-04-22T18:41:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fernando-de-marco-2.jpg\",\"contentUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fernando-de-marco-2.jpg\",\"width\":1840,\"height\":1004},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/\",\"name\":\"Prefeitura de Capivari\",\"description\":\"Prefeitura de Capivari\",\"publisher\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#organization\",\"name\":\"Prefeitura de Capivari\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-prefeitura-de-capivari.png\",\"contentUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-prefeitura-de-capivari.png\",\"width\":200,\"height\":147,\"caption\":\"Prefeitura de Capivari\"},\"image\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PrefeituradeCapivari\\\/\",\"https:\\\/\\\/x.com\\\/PrefCapivari\",\"https:\\\/\\\/www.instagram.com\\\/prefeituracapivari\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/person\\\/98801614a91d449946b0687ae2db9f29\",\"name\":\"Thalles Cristiano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g\",\"caption\":\"Thalles Cristiano\"},\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/author\\\/thalles-cristiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024 - Prefeitura de Capivari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/","og_locale":"pt_BR","og_type":"article","og_title":"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024 - Prefeitura de Capivari","og_description":"No \u00faltimo domingo, dia 21, teve in\u00edcio a segunda rodada do Campeonato Veterano de Futebol Amador. O dia tamb\u00e9m contou com a conclus\u00e3o da primeira rodada, totalizando tr\u00eas jogos em duas localidades diferentes. Veteranos Elias Fausto e Central venceram seus jogos e foram as manchetes do dia, no torneio que conta com a presen\u00e7a apenas [&hellip;]","og_url":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/","og_site_name":"Prefeitura de Capivari","article_publisher":"https:\/\/www.facebook.com\/PrefeituradeCapivari\/","article_published_time":"2024-04-22T18:41:43+00:00","og_image":[{"width":1840,"height":1004,"url":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/04\/fernando-de-marco-2.jpg","type":"image\/jpeg"}],"author":"Thalles Cristiano","twitter_card":"summary_large_image","twitter_creator":"@PrefCapivari","twitter_site":"@PrefCapivari","twitter_misc":{"Escrito por":"Thalles Cristiano","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#article","isPartOf":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/"},"author":{"name":"Thalles Cristiano","@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/person\/98801614a91d449946b0687ae2db9f29"},"headline":"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024","datePublished":"2024-04-22T18:41:43+00:00","mainEntityOfPage":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#organization"},"image":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/04\/fernando-de-marco-2.jpg","articleSection":["Destaque","Esporte","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/","url":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/","name":"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024 - Prefeitura de Capivari","isPartOf":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#primaryimage"},"image":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/04\/fernando-de-marco-2.jpg","datePublished":"2024-04-22T18:41:43+00:00","breadcrumb":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#primaryimage","url":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/04\/fernando-de-marco-2.jpg","contentUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/04\/fernando-de-marco-2.jpg","width":1840,"height":1004},{"@type":"BreadcrumbList","@id":"https:\/\/capivari.sp.gov.br\/portal\/veteranos-elias-fausto-e-central-vencem-em-segundo-dia-de-competicoes-do-campeonato-veterano-de-futebol-amador-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/capivari.sp.gov.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Veteranos Elias Fausto e Central vencem em segundo dia de competi\u00e7\u00f5es do Campeonato Veterano de Futebol Amador 2024"}]},{"@type":"WebSite","@id":"https:\/\/capivari.sp.gov.br\/portal\/#website","url":"https:\/\/capivari.sp.gov.br\/portal\/","name":"Prefeitura de Capivari","description":"Prefeitura de Capivari","publisher":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/capivari.sp.gov.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/capivari.sp.gov.br\/portal\/#organization","name":"Prefeitura de Capivari","url":"https:\/\/capivari.sp.gov.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2021\/09\/logo-prefeitura-de-capivari.png","contentUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2021\/09\/logo-prefeitura-de-capivari.png","width":200,"height":147,"caption":"Prefeitura de Capivari"},"image":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PrefeituradeCapivari\/","https:\/\/x.com\/PrefCapivari","https:\/\/www.instagram.com\/prefeituracapivari\/"]},{"@type":"Person","@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/person\/98801614a91d449946b0687ae2db9f29","name":"Thalles Cristiano","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g","caption":"Thalles Cristiano"},"url":"https:\/\/capivari.sp.gov.br\/portal\/author\/thalles-cristiano\/"}]}},"_links":{"self":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts\/17128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/comments?post=17128"}],"version-history":[{"count":1,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts\/17128\/revisions"}],"predecessor-version":[{"id":17129,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts\/17128\/revisions\/17129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/media\/17120"}],"wp:attachment":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/media?parent=17128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/categories?post=17128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/tags?post=17128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}