{"id":17612,"date":"2024-07-02T17:04:08","date_gmt":"2024-07-02T20:04:08","guid":{"rendered":"https:\/\/capivari.sp.gov.br\/portal\/?p=17612"},"modified":"2024-07-02T17:04:08","modified_gmt":"2024-07-02T20:04:08","slug":"porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao","status":"publish","type":"post","link":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/","title":{"rendered":"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o"},"content":{"rendered":"<p>No \u00faltimo s\u00e1bado, dia 29, aconteceram quatro partidas v\u00e1lidas pela terceira e quarta rodada da segunda divis\u00e3o do Campeonato Amador de Futebol, torneio que conta com a participa\u00e7\u00e3o de 13 equipes divididas em dois grupos. Com duas partidas no Est\u00e1dio Fernando de Marco e outras duas no Est\u00e1dio Jair Forti, o dia teve uma m\u00e9dia de dois gols por jogo.<\/p>\n<p>Confira o que rolou na divis\u00e3o de acesso do futebol capivariano:<\/p>\n<p>S\u00e3o Bento 0 x 1 Sport Capivari<\/p>\n<p>Com um jogo a menos, a equipe do Sport chegou a sua segunda vit\u00f3ria em dois jogos no \u00faltimo s\u00e1bado no Fernando de Marco. Com gol anotado por Lucas, a equipe vermelha e preta venceu pelo placar m\u00ednimo e ocupa a segunda posi\u00e7\u00e3o do grupo A, mesmo tendo folgado na primeira rodada. J\u00e1 a equipe do S\u00e3o Bento permanece com tr\u00eas pontos ganhos em duas partidas, j\u00e1 que folgaram na segunda rodada em raz\u00e3o do formato da competi\u00e7\u00e3o.<\/p>\n<p>Atl\u00e9tico Mombuca B 0 x 0 Ajax<\/p>\n<p>No primeiro empate sem gols da segunda divis\u00e3o, Atl\u00e9tico Mombuca B e Ajax n\u00e3o conseguiram encontrar o caminho das redes em partida que aconteceu no est\u00e1dio Jair Forti. Com o resultado, as equipes ocupam terceira e quarta posi\u00e7\u00f5es do grupo B, com sete e quatro pontos, respectivamente. \u00c9 importante destacar que a equipe do Ajax teve um jogo adiado na primeira rodada diante do Palmeirinha, que foi adiado para o dia 20 de julho.<\/p>\n<p>S\u00e3o Jo\u00e3o 3 x 2 Aston Villa<\/p>\n<p>Inaugurando os duelos da quarta rodada, S\u00e3o Jo\u00e3o e Aston Villa fizeram um bom jogo no est\u00e1dio Fernando de Marco. Com dois gols de Chin\u00eas e um de Ven\u00e2ncio, o S\u00e3o Jo\u00e3o venceu por 3-2 e chegou a nove pontos conquistados em quatro partidas at\u00e9 aqui. O Aston Villa, que marcou com Diego e Guilherme, segue sem marcar pontos no campeonato, com tr\u00eas derrotas em tr\u00eas jogos at\u00e9 aqui.<\/p>\n<p>Porto 1 x 1 Palmeirinha<\/p>\n<p>Em jogo que valia a lideran\u00e7a do grupo B do campeonato, Porto e Palmeirinha ficaram empatados em 1-1, em uma boa partida no est\u00e1dio Jair Forti. Jo\u00e3o Vitor anotou para a equipe do Porto, enquanto Djales igualou para o Palmeirinha. Com o resultado, ambos ficam com sete pontos ganhos, por\u00e9m o Palmeirinha possui um jogo a menos, em raz\u00e3o do adiamento do duelo da primeira rodada com o Ajax.<\/p>\n<p>Os dois melhores de cada grupo avan\u00e7am \u00e0s semifinais para disputar uma vaga na final e consequentemente o acesso \u00e0 elite de 2025. A quarta rodada do torneio tem sua conclus\u00e3o no pr\u00f3ximo fim de semana com os duelos entre Sparta e S\u00e3o Bento; Ribeir\u00e3o e Ajax; For\u00e7a Jovem e Sport Capivari e Uni\u00e3o e Atl\u00e9tico Mombuca B.<\/p>\n<p>Para saber mais sobre outros torneios e projetos organizados pela pasta, os telefones (19) 2146-1525 e (19) 3492-8881 (WhatsApp), est\u00e3o dispon\u00edveis de segunda a sexta-feira, das 8h30 \u00e0s 16h30.<\/p>\n<p>Prefeitura de Capivari. Transformando o presente, construindo o futuro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo s\u00e1bado, dia 29, aconteceram quatro partidas v\u00e1lidas pela terceira e quarta rodada da segunda divis\u00e3o do Campeonato Amador de Futebol, torneio que conta com a participa\u00e7\u00e3o de 13 equipes divididas em dois grupos. Com duas partidas no Est\u00e1dio Fernando de Marco e outras duas no Est\u00e1dio Jair Forti, o dia teve uma m\u00e9dia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[4,25,5],"tags":[],"class_list":["post-17612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-esporte","category-geral","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o - Prefeitura de Capivari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o - Prefeitura de Capivari\" \/>\n<meta property=\"og:description\" content=\"No \u00faltimo s\u00e1bado, dia 29, aconteceram quatro partidas v\u00e1lidas pela terceira e quarta rodada da segunda divis\u00e3o do Campeonato Amador de Futebol, torneio que conta com a participa\u00e7\u00e3o de 13 equipes divididas em dois grupos. Com duas partidas no Est\u00e1dio Fernando de Marco e outras duas no Est\u00e1dio Jair Forti, o dia teve uma m\u00e9dia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefeitura de Capivari\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PrefeituradeCapivari\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T20:04:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/06\/fernando-de-marco-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1840\" \/>\n\t<meta property=\"og:image:height\" content=\"1004\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thalles Cristiano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PrefCapivari\" \/>\n<meta name=\"twitter:site\" content=\"@PrefCapivari\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thalles Cristiano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/\"},\"author\":{\"name\":\"Thalles Cristiano\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/person\\\/98801614a91d449946b0687ae2db9f29\"},\"headline\":\"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o\",\"datePublished\":\"2024-07-02T20:04:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/\"},\"wordCount\":543,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/fernando-de-marco-1.jpg\",\"articleSection\":[\"Destaque\",\"Esporte\",\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/\",\"name\":\"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o - Prefeitura de Capivari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/fernando-de-marco-1.jpg\",\"datePublished\":\"2024-07-02T20:04:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/fernando-de-marco-1.jpg\",\"contentUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/fernando-de-marco-1.jpg\",\"width\":1840,\"height\":1004},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#website\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/\",\"name\":\"Prefeitura de Capivari\",\"description\":\"Prefeitura de Capivari\",\"publisher\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#organization\",\"name\":\"Prefeitura de Capivari\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-prefeitura-de-capivari.png\",\"contentUrl\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-prefeitura-de-capivari.png\",\"width\":200,\"height\":147,\"caption\":\"Prefeitura de Capivari\"},\"image\":{\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PrefeituradeCapivari\\\/\",\"https:\\\/\\\/x.com\\\/PrefCapivari\",\"https:\\\/\\\/www.instagram.com\\\/prefeituracapivari\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/#\\\/schema\\\/person\\\/98801614a91d449946b0687ae2db9f29\",\"name\":\"Thalles Cristiano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g\",\"caption\":\"Thalles Cristiano\"},\"url\":\"https:\\\/\\\/capivari.sp.gov.br\\\/portal\\\/author\\\/thalles-cristiano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o - Prefeitura de Capivari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/","og_locale":"pt_BR","og_type":"article","og_title":"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o - Prefeitura de Capivari","og_description":"No \u00faltimo s\u00e1bado, dia 29, aconteceram quatro partidas v\u00e1lidas pela terceira e quarta rodada da segunda divis\u00e3o do Campeonato Amador de Futebol, torneio que conta com a participa\u00e7\u00e3o de 13 equipes divididas em dois grupos. Com duas partidas no Est\u00e1dio Fernando de Marco e outras duas no Est\u00e1dio Jair Forti, o dia teve uma m\u00e9dia [&hellip;]","og_url":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/","og_site_name":"Prefeitura de Capivari","article_publisher":"https:\/\/www.facebook.com\/PrefeituradeCapivari\/","article_published_time":"2024-07-02T20:04:08+00:00","og_image":[{"width":1840,"height":1004,"url":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/06\/fernando-de-marco-1.jpg","type":"image\/jpeg"}],"author":"Thalles Cristiano","twitter_card":"summary_large_image","twitter_creator":"@PrefCapivari","twitter_site":"@PrefCapivari","twitter_misc":{"Escrito por":"Thalles Cristiano","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#article","isPartOf":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/"},"author":{"name":"Thalles Cristiano","@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/person\/98801614a91d449946b0687ae2db9f29"},"headline":"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o","datePublished":"2024-07-02T20:04:08+00:00","mainEntityOfPage":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/"},"wordCount":543,"commentCount":0,"publisher":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#organization"},"image":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#primaryimage"},"thumbnailUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/06\/fernando-de-marco-1.jpg","articleSection":["Destaque","Esporte","Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/","url":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/","name":"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o - Prefeitura de Capivari","isPartOf":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#primaryimage"},"image":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#primaryimage"},"thumbnailUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/06\/fernando-de-marco-1.jpg","datePublished":"2024-07-02T20:04:08+00:00","breadcrumb":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#primaryimage","url":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/06\/fernando-de-marco-1.jpg","contentUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2024\/06\/fernando-de-marco-1.jpg","width":1840,"height":1004},{"@type":"BreadcrumbList","@id":"https:\/\/capivari.sp.gov.br\/portal\/porto-e-palmeirinha-ficam-no-empate-pelo-grupo-b-sao-joao-vence-e-lidera-grupo-a-do-campeonato-amador-de-futebol-da-segunda-divisao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/capivari.sp.gov.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Porto e Palmeirinha ficam no empate pelo grupo B, S\u00e3o Jo\u00e3o vence e lidera grupo A do Campeonato Amador de Futebol da Segunda Divis\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/capivari.sp.gov.br\/portal\/#website","url":"https:\/\/capivari.sp.gov.br\/portal\/","name":"Prefeitura de Capivari","description":"Prefeitura de Capivari","publisher":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/capivari.sp.gov.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/capivari.sp.gov.br\/portal\/#organization","name":"Prefeitura de Capivari","url":"https:\/\/capivari.sp.gov.br\/portal\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/logo\/image\/","url":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2021\/09\/logo-prefeitura-de-capivari.png","contentUrl":"https:\/\/capivari.sp.gov.br\/portal\/wp-content\/uploads\/2021\/09\/logo-prefeitura-de-capivari.png","width":200,"height":147,"caption":"Prefeitura de Capivari"},"image":{"@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PrefeituradeCapivari\/","https:\/\/x.com\/PrefCapivari","https:\/\/www.instagram.com\/prefeituracapivari\/"]},{"@type":"Person","@id":"https:\/\/capivari.sp.gov.br\/portal\/#\/schema\/person\/98801614a91d449946b0687ae2db9f29","name":"Thalles Cristiano","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d1b9a4bdcde99ab11a8cd27abdcd088993749b82c4355c0301135023dc52b3d?s=96&d=mm&r=g","caption":"Thalles Cristiano"},"url":"https:\/\/capivari.sp.gov.br\/portal\/author\/thalles-cristiano\/"}]}},"_links":{"self":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts\/17612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/comments?post=17612"}],"version-history":[{"count":1,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts\/17612\/revisions"}],"predecessor-version":[{"id":17613,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/posts\/17612\/revisions\/17613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/media\/17529"}],"wp:attachment":[{"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/media?parent=17612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/categories?post=17612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/capivari.sp.gov.br\/portal\/wp-json\/wp\/v2\/tags?post=17612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}